{"id":4086,"date":"2025-08-30T11:26:27","date_gmt":"2025-08-30T10:26:27","guid":{"rendered":"https:\/\/www.mosigkau.net\/?p=4086"},"modified":"2025-08-30T11:26:27","modified_gmt":"2025-08-30T10:26:27","slug":"interaktiven-sightseeingtour-quer-durch-mosigkau","status":"publish","type":"post","link":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/","title":{"rendered":"interaktiven Sightseeingtour quer durch Mosigkau"},"content":{"rendered":"<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<h2 dir=\"auto\">interaktiven Sightseeingtour quer durch Mosigkau<\/h2>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Ihr erfahrt Wissenswertes rund um den Ort und seine Sehensw\u00fcrdigkeiten. Wer keine Lust zum Lesen auf dem Smartphone hat, kann sich die interessanten Inhalte auch bequem via Audioguide anh\u00f6ren.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">In dieser Woche war es endlich soweit. Als Arbeitsgruppe Digitalisierung konnten wir unser Projekt vorstellen. Auch die lokale Presse war geladen. Bei nicht ganz so gutem Wetter gaben wir alle wichtigen Infos zur gef\u00fchrten Radtour durch Mosigkau bekannt. (Mosigkau ist immer einen Besuch wert) F\u00fcr manche mag es kein gro\u00dfes Ereignis gewesen sein, f\u00fcr uns war es etwas ganz Besonderes. Dieses Projekt hat gezeigt, wie viel Freude ehrenamtliche Arbeit macht und was m\u00f6glich ist, wenn alle an einem Strang ziehen und ihre F\u00e4higkeiten einbringen.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">In wenigen Monaten brachten wir die digitale Tour von der Idee bis zum fertigen Guide. Das Projekt kann jederzeit erweitert werden und Gespr\u00e4che hierzu laufen bereits. Schon 2022 gab es eine Tour zum 750. Geburtstag Mosigkaus. Jan Bresching legte damals den Grundstein und trug viele Informationen zusammen. 2025 wurde das Konzept aufgegriffen und auf den aktuellen Stand gebracht. Sandra Gr\u00fcger leitete das Projekt organisatorisch und inhaltlich. Christin Hufm\u00fcller setzte die Inhalte in k\u00fcrzester Zeit in einer wunderbaren Karte technisch um (Dank auch an Heiko Schrenner). Fotos und Audioinhalte stammen von Ren\u00e9 (Lonko) Lonkowsky. Kristina Willfeld produzierte mit ihrer Firma Horizontwerbung die neuen wetterfesten Schilder.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Wenn ihr demn\u00e4chst in Mosigkau unterwegs seid und eines der Schilder entdeckt, scannt einfach den QR-Code und genie\u00dft eine informative Tour durch Mosigkau, die wir mit viel Herz und Hingabe gestaltet haben.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>interaktiven Sightseeingtour quer durch Mosigkau Ihr erfahrt Wissenswertes rund um den Ort und seine Sehensw\u00fcrdigkeiten. Wer<\/p>\n","protected":false},"author":2,"featured_media":4087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-4086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-startseite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)\" \/>\n<meta property=\"og:description\" content=\"interaktiven Sightseeingtour quer durch Mosigkau Ihr erfahrt Wissenswertes rund um den Ort und seine Sehensw\u00fcrdigkeiten. Wer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosigkau NET(T)\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-30T10:26:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jan Bresching\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jan Bresching\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/\"},\"author\":{\"name\":\"Jan Bresching\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/person\\\/2eb4a2cae570b3007fef9fcf558c062b\"},\"headline\":\"interaktiven Sightseeingtour quer durch Mosigkau\",\"datePublished\":\"2025-08-30T10:26:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/\"},\"wordCount\":270,\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sightseeing.png\",\"articleSection\":[\"Startseite\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/\",\"name\":\"interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sightseeing.png\",\"datePublished\":\"2025-08-30T10:26:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sightseeing.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sightseeing.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/interaktiven-sightseeingtour-quer-durch-mosigkau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"interaktiven Sightseeingtour quer durch Mosigkau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"name\":\"Mosigkau NET(T)\",\"description\":\"Informationen rund um Mosigkau\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\",\"name\":\"Mosigkau NET(T)\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"width\":512,\"height\":512,\"caption\":\"Mosigkau NET(T)\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/person\\\/2eb4a2cae570b3007fef9fcf558c062b\",\"name\":\"Jan Bresching\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/author\\\/bresching\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/","og_locale":"de_DE","og_type":"article","og_title":"interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)","og_description":"interaktiven Sightseeingtour quer durch Mosigkau Ihr erfahrt Wissenswertes rund um den Ort und seine Sehensw\u00fcrdigkeiten. Wer","og_url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/","og_site_name":"Mosigkau NET(T)","article_published_time":"2025-08-30T10:26:27+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png","type":"image\/png"}],"author":"Jan Bresching","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jan Bresching","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#article","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/"},"author":{"name":"Jan Bresching","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/person\/2eb4a2cae570b3007fef9fcf558c062b"},"headline":"interaktiven Sightseeingtour quer durch Mosigkau","datePublished":"2025-08-30T10:26:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/"},"wordCount":270,"publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png","articleSection":["Startseite"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/","name":"interaktiven Sightseeingtour quer durch Mosigkau - Mosigkau NET(T)","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#primaryimage"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png","datePublished":"2025-08-30T10:26:27+00:00","breadcrumb":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#primaryimage","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/sightseeing.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/interaktiven-sightseeingtour-quer-durch-mosigkau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/"},{"@type":"ListItem","position":2,"name":"interaktiven Sightseeingtour quer durch Mosigkau"}]},{"@type":"WebSite","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","name":"Mosigkau NET(T)","description":"Informationen rund um Mosigkau","publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization","name":"Mosigkau NET(T)","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","width":512,"height":512,"caption":"Mosigkau NET(T)"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/person\/2eb4a2cae570b3007fef9fcf558c062b","name":"Jan Bresching","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/author\/bresching\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:31:28","action":"change-status","newStatus":"trash","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/posts\/4086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/comments?post=4086"}],"version-history":[{"count":1,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/posts\/4086\/revisions"}],"predecessor-version":[{"id":4088,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/posts\/4086\/revisions\/4088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media\/4087"}],"wp:attachment":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media?parent=4086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/categories?post=4086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tags?post=4086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}