{"id":3877,"date":"2025-07-15T09:04:36","date_gmt":"2025-07-15T08:04:36","guid":{"rendered":"https:\/\/www.mosigkau.net\/?post_type=tribe_events&#038;p=3877"},"modified":"2025-07-15T09:04:36","modified_gmt":"2025-07-15T08:04:36","slug":"gemeindenachmittag-6","status":"publish","type":"tribe_events","link":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/","title":{"rendered":"Gemeindenachmittag"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":867,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3877","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemeindenachmittag - Mosigkau NET(T)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemeindenachmittag - Mosigkau NET(T)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosigkau NET(T)\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2022\/03\/kirche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"486\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/\",\"name\":\"Gemeindenachmittag - Mosigkau NET(T)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/kirche.png\",\"datePublished\":\"2025-07-15T08:04:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/kirche.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/kirche.png\",\"width\":486,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/gemeindenachmittag-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gemeindenachmittag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"name\":\"Mosigkau NET(T)\",\"description\":\"Informationen rund um Mosigkau\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\",\"name\":\"Mosigkau NET(T)\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"width\":512,\"height\":512,\"caption\":\"Mosigkau NET(T)\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemeindenachmittag - Mosigkau NET(T)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/","og_locale":"de_DE","og_type":"article","og_title":"Gemeindenachmittag - Mosigkau NET(T)","og_url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/","og_site_name":"Mosigkau NET(T)","og_image":[{"width":486,"height":648,"url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2022\/03\/kirche.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/","name":"Gemeindenachmittag - Mosigkau NET(T)","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/#primaryimage"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2022\/03\/kirche.png","datePublished":"2025-07-15T08:04:36+00:00","breadcrumb":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/#primaryimage","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2022\/03\/kirche.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2022\/03\/kirche.png","width":486,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/gemeindenachmittag-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/events\/"},{"@type":"ListItem","position":3,"name":"Gemeindenachmittag"}]},{"@type":"WebSite","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","name":"Mosigkau NET(T)","description":"Informationen rund um Mosigkau","publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization","name":"Mosigkau NET(T)","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","width":512,"height":512,"caption":"Mosigkau NET(T)"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/3877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/3877\/revisions"}],"predecessor-version":[{"id":3878,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/3877\/revisions\/3878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media\/867"}],"wp:attachment":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media?parent=3877"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tags?post=3877"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=3877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}