{"id":4397,"date":"2025-12-02T20:42:59","date_gmt":"2025-12-02T19:42:59","guid":{"rendered":"https:\/\/www.mosigkau.net\/?post_type=tribe_events&#038;p=4397"},"modified":"2025-12-02T20:42:59","modified_gmt":"2025-12-02T19:42:59","slug":"adventsnachmittag","status":"publish","type":"tribe_events","link":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/","title":{"rendered":"Adventsnachmittag"},"content":{"rendered":"<h2>Nachmittag im Advent<\/h2>\n<p>Am Donnerstag, dem 18.12. 2025 laden wir 14.30 Uhr ein zu<br \/>\neinem Adventsnachmittag bei Liedern und Geschichten zum<br \/>\nAdvent. Bei Kaffee und Geb\u00e4ck ist auch Zeit zum Erz\u00e4hlen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachmittag im Advent Am Donnerstag, dem 18.12. 2025 laden wir 14.30 Uhr ein zu einem Adventsnachmittag<\/p>\n","protected":false},"author":2,"featured_media":153,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4397","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adventsnachmittag - Mosigkau NET(T)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adventsnachmittag - Mosigkau NET(T)\" \/>\n<meta property=\"og:description\" content=\"Nachmittag im Advent Am Donnerstag, dem 18.12. 2025 laden wir 14.30 Uhr ein zu einem Adventsnachmittag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosigkau NET(T)\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2018\/12\/Martin-Luther-Kirche_Mosigkau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/\",\"name\":\"Adventsnachmittag - Mosigkau NET(T)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Martin-Luther-Kirche_Mosigkau.jpg\",\"datePublished\":\"2025-12-02T19:42:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Martin-Luther-Kirche_Mosigkau.jpg\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Martin-Luther-Kirche_Mosigkau.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/adventsnachmittag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adventsnachmittag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"name\":\"Mosigkau NET(T)\",\"description\":\"Informationen rund um Mosigkau\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\",\"name\":\"Mosigkau NET(T)\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"width\":512,\"height\":512,\"caption\":\"Mosigkau NET(T)\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adventsnachmittag - Mosigkau NET(T)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/","og_locale":"de_DE","og_type":"article","og_title":"Adventsnachmittag - Mosigkau NET(T)","og_description":"Nachmittag im Advent Am Donnerstag, dem 18.12. 2025 laden wir 14.30 Uhr ein zu einem Adventsnachmittag","og_url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/","og_site_name":"Mosigkau NET(T)","og_image":[{"width":1280,"height":960,"url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2018\/12\/Martin-Luther-Kirche_Mosigkau.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/","name":"Adventsnachmittag - Mosigkau NET(T)","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/#primaryimage"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2018\/12\/Martin-Luther-Kirche_Mosigkau.jpg","datePublished":"2025-12-02T19:42:59+00:00","breadcrumb":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/#primaryimage","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2018\/12\/Martin-Luther-Kirche_Mosigkau.jpg","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2018\/12\/Martin-Luther-Kirche_Mosigkau.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/adventsnachmittag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/events\/"},{"@type":"ListItem","position":3,"name":"Adventsnachmittag"}]},{"@type":"WebSite","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","name":"Mosigkau NET(T)","description":"Informationen rund um Mosigkau","publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization","name":"Mosigkau NET(T)","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","width":512,"height":512,"caption":"Mosigkau NET(T)"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4397\/revisions"}],"predecessor-version":[{"id":4398,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4397\/revisions\/4398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media\/153"}],"wp:attachment":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media?parent=4397"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tags?post=4397"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=4397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}