{"id":4545,"date":"2026-01-25T10:47:34","date_gmt":"2026-01-25T09:47:34","guid":{"rendered":"https:\/\/www.mosigkau.net\/?post_type=tribe_events&#038;p=4545"},"modified":"2026-01-25T10:47:34","modified_gmt":"2026-01-25T09:47:34","slug":"mdr-hol-dir-deine-show","status":"publish","type":"tribe_events","link":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/","title":{"rendered":"MDR- \u201eHol dir deine Show\u201c"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4546,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4545","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosigkau NET(T)\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2026\/01\/hol_show.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/\",\"name\":\"MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/hol_show.png\",\"datePublished\":\"2026-01-25T09:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/hol_show.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/hol_show.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/mdr-hol-dir-deine-show\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MDR- \u201eHol dir deine Show\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"name\":\"Mosigkau NET(T)\",\"description\":\"Informationen rund um Mosigkau\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\",\"name\":\"Mosigkau NET(T)\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"width\":512,\"height\":512,\"caption\":\"Mosigkau NET(T)\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/","og_locale":"de_DE","og_type":"article","og_title":"MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)","og_url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/","og_site_name":"Mosigkau NET(T)","og_image":[{"width":300,"height":300,"url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2026\/01\/hol_show.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/","name":"MDR- \u201eHol dir deine Show\u201c - Mosigkau NET(T)","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/#primaryimage"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2026\/01\/hol_show.png","datePublished":"2026-01-25T09:47:34+00:00","breadcrumb":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/#primaryimage","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2026\/01\/hol_show.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2026\/01\/hol_show.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/mdr-hol-dir-deine-show\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/events\/"},{"@type":"ListItem","position":3,"name":"MDR- \u201eHol dir deine Show\u201c"}]},{"@type":"WebSite","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","name":"Mosigkau NET(T)","description":"Informationen rund um Mosigkau","publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization","name":"Mosigkau NET(T)","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","width":512,"height":512,"caption":"Mosigkau NET(T)"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4545\/revisions"}],"predecessor-version":[{"id":4547,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4545\/revisions\/4547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media\/4546"}],"wp:attachment":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media?parent=4545"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tags?post=4545"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=4545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}