{"id":4678,"date":"2026-04-20T07:52:30","date_gmt":"2026-04-20T06:52:30","guid":{"rendered":"https:\/\/www.mosigkau.net\/?post_type=tribe_events&#038;p=4678"},"modified":"2026-04-20T07:52:30","modified_gmt":"2026-04-20T06:52:30","slug":"harfenmusik","status":"publish","type":"tribe_events","link":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/","title":{"rendered":"Harfenmusik"},"content":{"rendered":"<p>im Festsaal<\/p>\n<p>\u201eNordische Ballade- Adolf Sj\u00f6d\u00e9n und<br \/>\nseine Zeit\u201c<br \/>\nWerke von Sj\u00f6den, Brahms, Pratt\u00e9,<br \/>\nPoenitz, Spohr u.a.<br \/>\nmit Prof. Viktor Hatobanu (Harfe)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>im Festsaal \u201eNordische Ballade- Adolf Sj\u00f6d\u00e9n und seine Zeit\u201c Werke von Sj\u00f6den, Brahms, Pratt\u00e9, Poenitz, Spohr<\/p>\n","protected":false},"author":2,"featured_media":3944,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4678","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Harfenmusik - Mosigkau NET(T)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harfenmusik - Mosigkau NET(T)\" \/>\n<meta property=\"og:description\" content=\"im Festsaal \u201eNordische Ballade- Adolf Sj\u00f6d\u00e9n und seine Zeit\u201c Werke von Sj\u00f6den, Brahms, Pratt\u00e9, Poenitz, Spohr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosigkau NET(T)\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2025\/08\/schloss2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/\",\"name\":\"Harfenmusik - Mosigkau NET(T)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/schloss2.jpg\",\"datePublished\":\"2026-04-20T06:52:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/schloss2.jpg\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/schloss2.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/event\\\/harfenmusik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Harfenmusik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"name\":\"Mosigkau NET(T)\",\"description\":\"Informationen rund um Mosigkau\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#organization\",\"name\":\"Mosigkau NET(T)\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"contentUrl\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/wappen.png\",\"width\":512,\"height\":512,\"caption\":\"Mosigkau NET(T)\"},\"image\":{\"@id\":\"https:\\\/\\\/mosigkau-net.datel-dessau.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harfenmusik - Mosigkau NET(T)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/","og_locale":"de_DE","og_type":"article","og_title":"Harfenmusik - Mosigkau NET(T)","og_description":"im Festsaal \u201eNordische Ballade- Adolf Sj\u00f6d\u00e9n und seine Zeit\u201c Werke von Sj\u00f6den, Brahms, Pratt\u00e9, Poenitz, Spohr","og_url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/","og_site_name":"Mosigkau NET(T)","og_image":[{"width":800,"height":533,"url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2025\/08\/schloss2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/","name":"Harfenmusik - Mosigkau NET(T)","isPartOf":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/#primaryimage"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/#primaryimage"},"thumbnailUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/schloss2.jpg","datePublished":"2026-04-20T06:52:30+00:00","breadcrumb":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/#primaryimage","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/schloss2.jpg","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-content\/uploads\/2025\/08\/schloss2.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/event\/harfenmusik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/events\/"},{"@type":"ListItem","position":3,"name":"Harfenmusik"}]},{"@type":"WebSite","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#website","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","name":"Mosigkau NET(T)","description":"Informationen rund um Mosigkau","publisher":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#organization","name":"Mosigkau NET(T)","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","contentUrl":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/cms\/wp-content\/uploads\/2021\/08\/wappen.png","width":512,"height":512,"caption":"Mosigkau NET(T)"},"image":{"@id":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4678\/revisions"}],"predecessor-version":[{"id":4679,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4678\/revisions\/4679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media\/3944"}],"wp:attachment":[{"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/media?parent=4678"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tags?post=4678"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/mosigkau-net.datel-dessau.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=4678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}